{"id":6332,"date":"2024-04-11T16:32:32","date_gmt":"2024-04-11T14:32:32","guid":{"rendered":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1.jpg"},"modified":"2024-04-11T16:32:32","modified_gmt":"2024-04-11T14:32:32","slug":"winter-2024-1-52-2","status":"inherit","type":"attachment","link":"https:\/\/medsevens.fr\/en\/accueil\/med-sevens\/attachment\/winter-2024-1-52-2\/","title":{"rendered":"Winter 2024-1-52"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6332","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Winter 2024-1-52 - Esprit Sud Sevens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winter 2024-1-52 - Esprit Sud Sevens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Esprit Sud Sevens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/espritsudsevens\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@espritsud7\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Winter-2024-1-52-1-scaled.jpg\",\"url\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Winter-2024-1-52-1-scaled.jpg\",\"name\":\"Winter 2024-1-52 - Esprit Sud Sevens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#website\"},\"datePublished\":\"2024-04-11T14:32:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Winter-2024-1-52-1-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Winter-2024-1-52-1-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Winter-2024-1-52-1-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medsevens.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/medsevens.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Med Sevens\",\"item\":\"https:\\\/\\\/medsevens.fr\\\/accueil\\\/med-sevens\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Winter 2024-1-52\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#website\",\"url\":\"https:\\\/\\\/medsevens.fr\\\/\",\"name\":\"Esprit Sud Sevens\",\"description\":\"Sea, Sun and Sevens\",\"publisher\":{\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medsevens.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#organization\",\"name\":\"Esprit Sud Sevenes\",\"url\":\"https:\\\/\\\/medsevens.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sans-titre-1.png\",\"contentUrl\":\"https:\\\/\\\/medsevens.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sans-titre-1.png\",\"width\":150,\"height\":150,\"caption\":\"Esprit Sud Sevenes\"},\"image\":{\"@id\":\"https:\\\/\\\/medsevens.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espritsudsevens\\\/\",\"https:\\\/\\\/x.com\\\/espritsud7\",\"https:\\\/\\\/www.instagram.com\\\/espritsudsevens\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/46645187\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLxo6q7LE_zP7fVXGtgvvtQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winter 2024-1-52 - Esprit Sud Sevens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg","og_locale":"en_GB","og_type":"article","og_title":"Winter 2024-1-52 - Esprit Sud Sevens","og_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg","og_site_name":"Esprit Sud Sevens","article_publisher":"https:\/\/www.facebook.com\/espritsudsevens\/","og_image":[{"url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@espritsud7","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg","url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg","name":"Winter 2024-1-52 - Esprit Sud Sevens","isPartOf":{"@id":"https:\/\/medsevens.fr\/#website"},"datePublished":"2024-04-11T14:32:32+00:00","breadcrumb":{"@id":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medsevens.fr\/"},{"@type":"ListItem","position":2,"name":"Accueil","item":"https:\/\/medsevens.fr\/"},{"@type":"ListItem","position":3,"name":"Med Sevens","item":"https:\/\/medsevens.fr\/accueil\/med-sevens\/"},{"@type":"ListItem","position":4,"name":"Winter 2024-1-52"}]},{"@type":"WebSite","@id":"https:\/\/medsevens.fr\/#website","url":"https:\/\/medsevens.fr\/","name":"Esprit Sud Sevens","description":"Sea, Sun and Sevens","publisher":{"@id":"https:\/\/medsevens.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medsevens.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/medsevens.fr\/#organization","name":"Esprit Sud Sevenes","url":"https:\/\/medsevens.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/medsevens.fr\/#\/schema\/logo\/image\/","url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2020\/04\/Sans-titre-1.png","contentUrl":"https:\/\/medsevens.fr\/wp-content\/uploads\/2020\/04\/Sans-titre-1.png","width":150,"height":150,"caption":"Esprit Sud Sevenes"},"image":{"@id":"https:\/\/medsevens.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espritsudsevens\/","https:\/\/x.com\/espritsud7","https:\/\/www.instagram.com\/espritsudsevens\/","https:\/\/www.linkedin.com\/company\/46645187\/","https:\/\/www.youtube.com\/channel\/UCLxo6q7LE_zP7fVXGtgvvtQ"]}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-200x300.jpg 200w, https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled-600x900.jpg 600w, https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-683x1024.jpg 683w, https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-768x1152.jpg 768w, https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-247x370.jpg 247w, https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1707,"height":2560,"file":"2024\/04\/Winter-2024-1-52-1-scaled.jpg","filesize":857511,"sizes":{"woocommerce_thumbnail":{"file":"Winter-2024-1-52-1-scaled-300x300.jpg","width":300,"height":300,"filesize":66439,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"Winter-2024-1-52-1-scaled-100x100.jpg","width":100,"height":100,"filesize":41063,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled-100x100.jpg"},"woocommerce_single":{"file":"Winter-2024-1-52-1-scaled-600x900.jpg","width":600,"height":900,"filesize":176715,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled-600x900.jpg"},"medium":{"file":"Winter-2024-1-52-1-200x300.jpg","width":200,"height":300,"filesize":57521,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-200x300.jpg"},"large":{"file":"Winter-2024-1-52-1-683x1024.jpg","width":683,"height":1024,"filesize":213415,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-683x1024.jpg"},"thumbnail":{"file":"Winter-2024-1-52-1-150x150.jpg","width":150,"height":150,"filesize":45447,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-150x150.jpg"},"medium_large":{"file":"Winter-2024-1-52-1-768x1152.jpg","width":768,"height":1152,"filesize":252045,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-768x1152.jpg"},"recent_football":{"file":"Winter-2024-1-52-1-247x370.jpg","width":247,"height":370,"filesize":67043,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-247x370.jpg"},"full":{"file":"Winter-2024-1-52-1-scaled.jpg","width":1707,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg"}},"image_meta":{"aperture":"5","credit":"","camera":"Canon EOS R7","caption":"","created_timestamp":"1710588431","copyright":"","focal_length":"40","iso":"160","shutter_speed":"0.0008","title":"","orientation":"0","keywords":[]}},"post":3285,"source_url":"https:\/\/medsevens.fr\/wp-content\/uploads\/2024\/04\/Winter-2024-1-52-1-scaled.jpg","filename":"Winter-2024-1-52-1-scaled.jpg","filesize":857511,"_links":{"self":[{"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/media\/6332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/comments?post=6332"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":3285,"href":"https:\/\/medsevens.fr\/en\/wp-json\/wp\/v2\/pages\/3285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}